{"id":166,"count":1,"description":"","link":"https:\/\/ment.si\/en\/genre\/classical\/","name":"Classical","slug":"classical","taxonomy":"genre","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ment.si\/en\/wp-json\/wp\/v2\/genre\/166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ment.si\/en\/wp-json\/wp\/v2\/genre"}],"about":[{"href":"https:\/\/ment.si\/en\/wp-json\/wp\/v2\/taxonomies\/genre"}],"wp:post_type":[{"href":"https:\/\/ment.si\/en\/wp-json\/wp\/v2\/artist?genre=166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}