{"id":158,"count":0,"description":"","link":"https:\/\/ment.si\/en\/genre\/psychedelic-microtonal-jazz\/","name":"Psychedelic microtonal jazz","slug":"psychedelic-microtonal-jazz","taxonomy":"genre","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ment.si\/en\/wp-json\/wp\/v2\/genre\/158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ment.si\/en\/wp-json\/wp\/v2\/genre"}],"about":[{"href":"https:\/\/ment.si\/en\/wp-json\/wp\/v2\/taxonomies\/genre"}],"wp:post_type":[{"href":"https:\/\/ment.si\/en\/wp-json\/wp\/v2\/artist?genre=158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}